{"id":2474,"date":"2026-08-24T17:01:18","date_gmt":"2026-08-24T14:01:18","guid":{"rendered":"https:\/\/mylopotamosonline.crowdapps.cloud\/epixeirisi\/pool-bar-2\/"},"modified":"2026-08-24T17:01:18","modified_gmt":"2026-08-24T14:01:18","slug":"pool-bar-2","status":"publish","type":"epixeirisi","link":"https:\/\/mylopotamosonline.crowdapps.cloud\/en\/epixeirisi\/pool-bar-2\/","title":{"rendered":"Pool Bar"},"author":1,"featured_media":0,"template":"","epixeirisi_category":[108,36],"class_list":["post-2474","epixeirisi","type-epixeirisi","status-publish","hentry","epixeirisi_category-bars-nightlife","epixeirisi_category-food-drink-en"],"acf":[],"_links":{"self":[{"href":"https:\/\/mylopotamosonline.crowdapps.cloud\/en\/wp-json\/wp\/v2\/epixeirisi\/2474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mylopotamosonline.crowdapps.cloud\/en\/wp-json\/wp\/v2\/epixeirisi"}],"about":[{"href":"https:\/\/mylopotamosonline.crowdapps.cloud\/en\/wp-json\/wp\/v2\/types\/epixeirisi"}],"author":[{"embeddable":true,"href":"https:\/\/mylopotamosonline.crowdapps.cloud\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/mylopotamosonline.crowdapps.cloud\/en\/wp-json\/wp\/v2\/media?parent=2474"}],"wp:term":[{"taxonomy":"epixeirisi_category","embeddable":true,"href":"https:\/\/mylopotamosonline.crowdapps.cloud\/en\/wp-json\/wp\/v2\/epixeirisi_category?post=2474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}